{"id":3313,"date":"2026-08-21T07:01:25","date_gmt":"2026-08-21T07:01:25","guid":{"rendered":"https:\/\/hosannaskincare.com\/home\/"},"modified":"2026-08-22T20:36:47","modified_gmt":"2026-08-22T20:36:47","slug":"home","status":"publish","type":"page","link":"https:\/\/hosannaskincare.com\/es\/","title":{"rendered":"Hogar"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"nf_dc_page":"","_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-3313","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - Hosanna Skin Care<\/title>\n<meta name=\"description\" content=\"We sell sustainable, organic, natural, handmade, and toxic free products\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hosannaskincare.com\/es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Hosanna Skin Care\" \/>\n<meta property=\"og:description\" content=\"We sell sustainable, organic, natural, handmade, and toxic free products\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hosannaskincare.com\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"Hosanna Skin Care\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-22T20:36:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/hosannaskincare.com\/wp-content\/uploads\/2026\/08\/hosanna-social-card-1200x630-1.jpg?fit=1200%2C630&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"We sell sustainable, organic, natural, handmade, and toxic free products\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/i0.wp.com\/hosannaskincare.com\/wp-content\/uploads\/2026\/08\/general.webp?fit=1920%2C900&ssl=1\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hosannaskincare.com\\\/\",\"url\":\"https:\\\/\\\/hosannaskincare.com\\\/\",\"name\":\"Home - Hosanna Skin Care\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hosannaskincare.com\\\/#website\"},\"datePublished\":\"2026-08-21T07:01:25+00:00\",\"dateModified\":\"2026-08-22T20:36:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hosannaskincare.com\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hosannaskincare.com\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hosannaskincare.com\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hosannaskincare.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hosannaskincare.com\\\/#website\",\"url\":\"https:\\\/\\\/hosannaskincare.com\\\/\",\"name\":\"hosannaskincare.com\",\"description\":\"We sell sustainable, organic, natural, handmade, and toxic free products\",\"publisher\":{\"@id\":\"https:\\\/\\\/hosannaskincare.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hosannaskincare.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hosannaskincare.com\\\/#organization\",\"name\":\"Hosanna Skin Care\",\"url\":\"https:\\\/\\\/hosannaskincare.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hosannaskincare.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hosannaskincare.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Hosanna-SkinCare-icono-inicio-01-1.jpg\",\"contentUrl\":\"https:\\\/\\\/hosannaskincare.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Hosanna-SkinCare-icono-inicio-01-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Hosanna Skin Care\"},\"image\":{\"@id\":\"https:\\\/\\\/hosannaskincare.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/hosannaskincare\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inicio - Cuidado de la piel Hosanna","description":"Vendemos productos sustentables, org\u00e1nicos, naturales, hechos a mano y libres de t\u00f3xicos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hosannaskincare.com\/es\/","og_locale":"es_ES","og_type":"article","og_title":"Home - Hosanna Skin Care","og_description":"We sell sustainable, organic, natural, handmade, and toxic free products","og_url":"https:\/\/hosannaskincare.com\/es\/","og_site_name":"Hosanna Skin Care","article_modified_time":"2026-08-22T20:36:47+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/i0.wp.com\/hosannaskincare.com\/wp-content\/uploads\/2026\/08\/hosanna-social-card-1200x630-1.jpg?fit=1200%2C630&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"We sell sustainable, organic, natural, handmade, and toxic free products","twitter_image":"https:\/\/i0.wp.com\/hosannaskincare.com\/wp-content\/uploads\/2026\/08\/general.webp?fit=1920%2C900&ssl=1","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hosannaskincare.com\/","url":"https:\/\/hosannaskincare.com\/","name":"Inicio - Cuidado de la piel Hosanna","isPartOf":{"@id":"https:\/\/hosannaskincare.com\/#website"},"datePublished":"2026-08-21T07:01:25+00:00","dateModified":"2026-08-22T20:36:47+00:00","breadcrumb":{"@id":"https:\/\/hosannaskincare.com\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hosannaskincare.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hosannaskincare.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hosannaskincare.com\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/hosannaskincare.com\/#website","url":"https:\/\/hosannaskincare.com\/","name":"hosannaskincare.com","description":"Vendemos productos sustentables, org\u00e1nicos, naturales, hechos a mano y libres de t\u00f3xicos.","publisher":{"@id":"https:\/\/hosannaskincare.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hosannaskincare.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hosannaskincare.com\/#organization","name":"Hosanna Cuidado de la Piel","url":"https:\/\/hosannaskincare.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hosannaskincare.com\/#\/schema\/logo\/image\/","url":"https:\/\/hosannaskincare.com\/wp-content\/uploads\/2023\/05\/cropped-Hosanna-SkinCare-icono-inicio-01-1.jpg","contentUrl":"https:\/\/hosannaskincare.com\/wp-content\/uploads\/2023\/05\/cropped-Hosanna-SkinCare-icono-inicio-01-1.jpg","width":512,"height":512,"caption":"Hosanna Skin Care"},"image":{"@id":"https:\/\/hosannaskincare.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/hosannaskincare\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/hosannaskincare.com\/es\/wp-json\/wp\/v2\/pages\/3313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hosannaskincare.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hosannaskincare.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hosannaskincare.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hosannaskincare.com\/es\/wp-json\/wp\/v2\/comments?post=3313"}],"version-history":[{"count":1,"href":"https:\/\/hosannaskincare.com\/es\/wp-json\/wp\/v2\/pages\/3313\/revisions"}],"predecessor-version":[{"id":3589,"href":"https:\/\/hosannaskincare.com\/es\/wp-json\/wp\/v2\/pages\/3313\/revisions\/3589"}],"wp:attachment":[{"href":"https:\/\/hosannaskincare.com\/es\/wp-json\/wp\/v2\/media?parent=3313"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}